{"id":63092,"date":"2026-01-10T16:19:49","date_gmt":"2026-01-10T21:19:49","guid":{"rendered":"https:\/\/gentologie.com\/?page_id=63092"},"modified":"2026-01-10T16:27:24","modified_gmt":"2026-01-10T21:27:24","slug":"finances","status":"publish","type":"page","link":"https:\/\/gentologie.com\/en\/business\/finances\/","title":{"rendered":"Finances"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":63083,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-gentologie-pages.php","meta":{"footnotes":""},"coauthors":[5548],"class_list":["post-63092","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finances | Gentologie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gentologie.com\/en\/business\/finances\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finances | Gentologie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gentologie.com\/en\/business\/finances\/\" \/>\n<meta property=\"og:site_name\" content=\"Gentologie\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/gentologie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-10T21:27:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gentologie.com\/wp-content\/uploads\/2026\/02\/Gentologie-Logo-Yoast-Fallback.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Normand Boulanger\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/business\\\/finances\\\/\",\"url\":\"https:\\\/\\\/gentologie.com\\\/en\\\/business\\\/finances\\\/\",\"name\":\"Finances | Gentologie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/#website\"},\"datePublished\":\"2026-01-10T21:19:49+00:00\",\"dateModified\":\"2026-01-10T21:27:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/business\\\/finances\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gentologie.com\\\/en\\\/business\\\/finances\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/business\\\/finances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gentologie.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business\",\"item\":\"https:\\\/\\\/gentologie.com\\\/en\\\/business\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Finances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gentologie.com\\\/en\\\/\",\"name\":\"Gentologie\",\"description\":\"Style de Vie pour Gentleman | Lifestyle for Gentleman\",\"publisher\":{\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gentologie.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/#organization\",\"name\":\"Gentologie\",\"url\":\"https:\\\/\\\/gentologie.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gentologie.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Gentologie-Logo-Site-IMG.jpg\",\"contentUrl\":\"https:\\\/\\\/gentologie.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Gentologie-Logo-Site-IMG.jpg\",\"width\":696,\"height\":696,\"caption\":\"Gentologie\"},\"image\":{\"@id\":\"https:\\\/\\\/gentologie.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/gentologie\",\"http:\\\/\\\/instagram.com\\\/gentologie\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gentologie\",\"https:\\\/\\\/www.pinterest.com\\\/gentologie\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@gentologie\",\"https:\\\/\\\/www.threads.com\\\/@gentologie\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finances | Gentologie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gentologie.com\/en\/business\/finances\/","og_locale":"en_US","og_type":"article","og_title":"Finances | Gentologie","og_url":"https:\/\/gentologie.com\/en\/business\/finances\/","og_site_name":"Gentologie","article_publisher":"http:\/\/facebook.com\/gentologie","article_modified_time":"2026-01-10T21:27:24+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/gentologie.com\/wp-content\/uploads\/2026\/02\/Gentologie-Logo-Yoast-Fallback.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Normand Boulanger"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gentologie.com\/en\/business\/finances\/","url":"https:\/\/gentologie.com\/en\/business\/finances\/","name":"Finances | Gentologie","isPartOf":{"@id":"https:\/\/gentologie.com\/en\/#website"},"datePublished":"2026-01-10T21:19:49+00:00","dateModified":"2026-01-10T21:27:24+00:00","breadcrumb":{"@id":"https:\/\/gentologie.com\/en\/business\/finances\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gentologie.com\/en\/business\/finances\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gentologie.com\/en\/business\/finances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gentologie.com\/en\/"},{"@type":"ListItem","position":2,"name":"Business","item":"https:\/\/gentologie.com\/en\/business\/"},{"@type":"ListItem","position":3,"name":"Finances"}]},{"@type":"WebSite","@id":"https:\/\/gentologie.com\/en\/#website","url":"https:\/\/gentologie.com\/en\/","name":"Gentologie","description":"Style de Vie pour Gentleman | Lifestyle for Gentleman","publisher":{"@id":"https:\/\/gentologie.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gentologie.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gentologie.com\/en\/#organization","name":"Gentologie","url":"https:\/\/gentologie.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gentologie.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gentologie.com\/wp-content\/uploads\/2026\/02\/Gentologie-Logo-Site-IMG.jpg","contentUrl":"https:\/\/gentologie.com\/wp-content\/uploads\/2026\/02\/Gentologie-Logo-Site-IMG.jpg","width":696,"height":696,"caption":"Gentologie"},"image":{"@id":"https:\/\/gentologie.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/gentologie","http:\/\/instagram.com\/gentologie","https:\/\/www.linkedin.com\/company\/gentologie","https:\/\/www.pinterest.com\/gentologie\/","https:\/\/www.youtube.com\/@gentologie","https:\/\/www.threads.com\/@gentologie"]}]}},"_links":{"self":[{"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/pages\/63092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/comments?post=63092"}],"version-history":[{"count":1,"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/pages\/63092\/revisions"}],"predecessor-version":[{"id":63094,"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/pages\/63092\/revisions\/63094"}],"up":[{"embeddable":true,"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/pages\/63083"}],"wp:attachment":[{"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/media?parent=63092"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/gentologie.com\/en\/wp-json\/wp\/v2\/coauthors?post=63092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}